{"id":2372,"date":"2014-11-03T00:00:00","date_gmt":"2014-11-02T23:00:00","guid":{"rendered":"https:\/\/rsm.dagostinofrancesco.com\/seniores-san-mauro-novara-20-27\/"},"modified":"2014-11-03T00:00:00","modified_gmt":"2014-11-02T23:00:00","slug":"seniores-san-mauro-novara-20-27","status":"publish","type":"post","link":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/","title":{"rendered":"Seniores San Mauro &#8211; Novara 20-27"},"content":{"rendered":"<p>Serie C 02\/11\/2014<br \/>\nTerreno di gioco in ottime condizioni ed una splendida giornata di sole a contorno della gara tra la capolista Novara \u00a0e la seconda in classifica. Il San Mauro ha preparatola gara, durante la settimana, tenendo presenti i punti di forza della formazione avversaria. La mischia e la rimessa laterale degli avversari sono state definite temibili da tutti gli avversari. Per trenta minuti il San Mauro gioca la gara perfetta e tiene testa nelle fasi ordinate mettendo in grosse difficolt\u00e0 gli avversari. L&#8217;unico errore e&#8217; nel punteggio,dopo trenta minuti \u00a0il risultato e&#8217; pareggio perfetto, zero a zero. Nei dieci minuti che seguono \u00a0sono \u00a0tre le mete realizzate una dal San Mauro con Dezzani e due dal Novara \u00a0con il pacchetto di mischia.\u00a0 Punteggio 12 \u00a0a 7 per gli ospiti al termine del primo tempo. Nella seconda frazione di gioco \u00a0la stanchezza inizia a farsi sentire e la mischia del San Mauro cala \u00a0di tono concedendo maggiori \u00a0spazi agli avversari .\u00a0<br \/>\nNovara ancora in meta a soli dieci minuti dal termine con la solita mischia che fa valere la maggior potenza fisica.Immediata la replica di Rosso che con un piazzato accorcia le distanze.\u00a0 La pressione dei gialloblu sembra finalmente fruttare una ottima opportunit\u00e0, ma a soli dieci metri dalla meta \u00a0un intercetto \u00a0segna un capovolgimento di fronte e la successiva meta novarese. La gara sembra ormai sfuggita di mano, soli dieci minuti residui sono di attacco incessante all&#8217;area di meta avversaria. Segna Dezzani, lo scarto e&#8217; ridotto , gli attacchi sono incessanti, ma ancora una volta la fortuna e&#8217; avversa. L&#8217;arbitro fischia l&#8217;ultimo fallo , Novara va in rimessa laterale e l&#8217;arbitro fischia il termine della gara. Adesso tre settimane di riposo per recuperare gli infortuni e presentarsi al girone di ritorno \u00a0in buone condizioni per l&#8217;accesso ai play-off.<\/p>\n<p>Formazione : \u00a0Catania, Perillo, Giacchino, Gastaldo, Buronzo, Gramadaermine, Marinotto, Ostallo, Rosso, Ardito, Paduano, Varricchio, Blieck, Faletti, Dezzani<\/p>\n<p>A disposizione: Armanni , Cammarata, Deletteriis, Balbo, Mariani, Sorrentino, Scaglione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Serie C 02\/11\/2014 Terreno di gioco in ottime condizioni ed una splendida giornata di sole a contorno della gara tra la capolista Novara \u00a0e la seconda in classifica. Il San Mauro ha preparatola gara, durante la settimana, tenendo presenti i punti di forza della formazione avversaria. La mischia e la rimessa laterale degli avversari sono [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2372","post","type-post","status-publish","format-standard","hentry","category-archivio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seniores San Mauro - Novara 20-27 - Rugby San Mauro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seniores San Mauro - Novara 20-27 - Rugby San Mauro\" \/>\n<meta property=\"og:description\" content=\"Serie C 02\/11\/2014 Terreno di gioco in ottime condizioni ed una splendida giornata di sole a contorno della gara tra la capolista Novara \u00a0e la seconda in classifica. Il San Mauro ha preparatola gara, durante la settimana, tenendo presenti i punti di forza della formazione avversaria. La mischia e la rimessa laterale degli avversari sono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/\" \/>\n<meta property=\"og:site_name\" content=\"Rugby San Mauro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rugbysanmauro\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-02T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Francesco002\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/\"},\"author\":{\"name\":\"Francesco002\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#\\\/schema\\\/person\\\/5752ef3556e19dd3efee8f9616d69256\"},\"headline\":\"Seniores San Mauro &#8211; Novara 20-27\",\"datePublished\":\"2014-11-02T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/\"},\"wordCount\":333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#organization\"},\"articleSection\":[\"Archivio\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/\",\"url\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/\",\"name\":\"Seniores San Mauro - Novara 20-27 - Rugby San Mauro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#website\"},\"datePublished\":\"2014-11-02T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/seniores-san-mauro-novara-20-27\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rugbysanmauro.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seniores San Mauro &#8211; Novara 20-27\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#website\",\"url\":\"https:\\\/\\\/rugbysanmauro.it\\\/\",\"name\":\"Rugby San Mauro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rugbysanmauro.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#organization\",\"name\":\"ASD Rugby San Mauro\",\"url\":\"https:\\\/\\\/rugbysanmauro.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rugbysanmauro.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Logo-San-Mauro-Rugby-scudo.webp\",\"contentUrl\":\"https:\\\/\\\/rugbysanmauro.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Logo-San-Mauro-Rugby-scudo.webp\",\"width\":512,\"height\":512,\"caption\":\"ASD Rugby San Mauro\"},\"image\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rugbysanmauro\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rugbysanmauro\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#\\\/schema\\\/person\\\/5752ef3556e19dd3efee8f9616d69256\",\"name\":\"Francesco002\",\"sameAs\":[\"https:\\\/\\\/rugbysanmauro.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seniores San Mauro - Novara 20-27 - Rugby San Mauro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/","og_locale":"it_IT","og_type":"article","og_title":"Seniores San Mauro - Novara 20-27 - Rugby San Mauro","og_description":"Serie C 02\/11\/2014 Terreno di gioco in ottime condizioni ed una splendida giornata di sole a contorno della gara tra la capolista Novara \u00a0e la seconda in classifica. Il San Mauro ha preparatola gara, durante la settimana, tenendo presenti i punti di forza della formazione avversaria. La mischia e la rimessa laterale degli avversari sono [&hellip;]","og_url":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/","og_site_name":"Rugby San Mauro","article_publisher":"https:\/\/www.facebook.com\/rugbysanmauro\/","article_published_time":"2014-11-02T23:00:00+00:00","author":"Francesco002","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/#article","isPartOf":{"@id":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/"},"author":{"name":"Francesco002","@id":"https:\/\/rugbysanmauro.it\/#\/schema\/person\/5752ef3556e19dd3efee8f9616d69256"},"headline":"Seniores San Mauro &#8211; Novara 20-27","datePublished":"2014-11-02T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/"},"wordCount":333,"commentCount":0,"publisher":{"@id":"https:\/\/rugbysanmauro.it\/#organization"},"articleSection":["Archivio"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/","url":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/","name":"Seniores San Mauro - Novara 20-27 - Rugby San Mauro","isPartOf":{"@id":"https:\/\/rugbysanmauro.it\/#website"},"datePublished":"2014-11-02T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rugbysanmauro.it\/index.php\/seniores-san-mauro-novara-20-27\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rugbysanmauro.it\/"},{"@type":"ListItem","position":2,"name":"Seniores San Mauro &#8211; Novara 20-27"}]},{"@type":"WebSite","@id":"https:\/\/rugbysanmauro.it\/#website","url":"https:\/\/rugbysanmauro.it\/","name":"Rugby San Mauro","description":"","publisher":{"@id":"https:\/\/rugbysanmauro.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rugbysanmauro.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/rugbysanmauro.it\/#organization","name":"ASD Rugby San Mauro","url":"https:\/\/rugbysanmauro.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rugbysanmauro.it\/#\/schema\/logo\/image\/","url":"https:\/\/rugbysanmauro.it\/wp-content\/uploads\/2025\/10\/Logo-San-Mauro-Rugby-scudo.webp","contentUrl":"https:\/\/rugbysanmauro.it\/wp-content\/uploads\/2025\/10\/Logo-San-Mauro-Rugby-scudo.webp","width":512,"height":512,"caption":"ASD Rugby San Mauro"},"image":{"@id":"https:\/\/rugbysanmauro.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rugbysanmauro\/","https:\/\/www.instagram.com\/rugbysanmauro\/"]},{"@type":"Person","@id":"https:\/\/rugbysanmauro.it\/#\/schema\/person\/5752ef3556e19dd3efee8f9616d69256","name":"Francesco002","sameAs":["https:\/\/rugbysanmauro.it"]}]}},"_links":{"self":[{"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/posts\/2372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/comments?post=2372"}],"version-history":[{"count":0,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/posts\/2372\/revisions"}],"wp:attachment":[{"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/media?parent=2372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/categories?post=2372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/tags?post=2372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}