{"id":1912,"date":"2020-03-05T00:00:00","date_gmt":"2020-03-04T23:00:00","guid":{"rendered":"https:\/\/rsm.dagostinofrancesco.com\/aggiornamento-del-5-marzo-covid-19-disposizioni\/"},"modified":"2020-03-05T00:00:00","modified_gmt":"2020-03-04T23:00:00","slug":"aggiornamento-del-5-marzo-covid-19-disposizioni","status":"publish","type":"post","link":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/","title":{"rendered":"aggiornamento del 5 marzo covid -19 disposizioni"},"content":{"rendered":"<p>In riferimento al comunicato della Presidenza del Consiglio del 4 marzo \u201920 riguardante le regole comportamentali e prudenziali per il contrasto e contenimento della diffusione del COVID-19, la Societ\u00e0 Rugby San Mauro ha deciso di interrompere tutte le attivit\u00e0 quali : allenamenti, partite amichevoli e tutte le attivit\u00e0 di preparazione atletica per tutte le categorie di ogni ordine e grado. ( dalla propaganda alla Seniores ) fino al 15 marzo 2020. Questa decisione scaturisce dall\u2019impossibilit\u00e0 di garantire uno dei presupposti indicati dalla circolare attuativa ( punto (d) mantenimento, nei contatti sociali, di una distanza interpersonale di almeno un metro) . Se verranno emessi nuovi comunicati ci adegueremo prontamente e comunicheremo a tutti le nuove indicazioni . Sperando di poter riprendere al pi\u00f9 presto le attivit\u00e0 sportive del nostro club rimaniamo a disposizione per eventuali chiarimenti .<br \/>\nLe succitate decisioni sono state prese a tutela degli atleti e dei loro familiari e in ottemperanza alle diposizioni Governative .<br \/>\nIl Direttivo<br \/>\nASD Rugby San Mauro<\/p>\n<p>https:\/\/www.ansa.it\/documents\/1583344838842_DPCM.pdf<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In riferimento al comunicato della Presidenza del Consiglio del 4 marzo \u201920 riguardante le regole comportamentali e prudenziali per il contrasto e contenimento della diffusione del COVID-19, la Societ\u00e0 Rugby San Mauro ha deciso di interrompere tutte le attivit\u00e0 quali : allenamenti, partite amichevoli e tutte le attivit\u00e0 di preparazione atletica per tutte le categorie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1912","post","type-post","status-publish","format-standard","hentry","category-archivio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>aggiornamento del 5 marzo covid -19 disposizioni - Rugby San Mauro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"aggiornamento del 5 marzo covid -19 disposizioni - Rugby San Mauro\" \/>\n<meta property=\"og:description\" content=\"In riferimento al comunicato della Presidenza del Consiglio del 4 marzo \u201920 riguardante le regole comportamentali e prudenziali per il contrasto e contenimento della diffusione del COVID-19, la Societ\u00e0 Rugby San Mauro ha deciso di interrompere tutte le attivit\u00e0 quali : allenamenti, partite amichevoli e tutte le attivit\u00e0 di preparazione atletica per tutte le categorie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Rugby San Mauro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rugbysanmauro\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-04T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Francesco002\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/\"},\"author\":{\"name\":\"Francesco002\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#\\\/schema\\\/person\\\/5752ef3556e19dd3efee8f9616d69256\"},\"headline\":\"aggiornamento del 5 marzo covid -19 disposizioni\",\"datePublished\":\"2020-03-04T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/\"},\"wordCount\":165,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#organization\"},\"articleSection\":[\"Archivio\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/\",\"url\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/\",\"name\":\"aggiornamento del 5 marzo covid -19 disposizioni - Rugby San Mauro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#website\"},\"datePublished\":\"2020-03-04T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/index.php\\\/aggiornamento-del-5-marzo-covid-19-disposizioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rugbysanmauro.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"aggiornamento del 5 marzo covid -19 disposizioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#website\",\"url\":\"https:\\\/\\\/rugbysanmauro.it\\\/\",\"name\":\"Rugby San Mauro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rugbysanmauro.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#organization\",\"name\":\"ASD Rugby San Mauro\",\"url\":\"https:\\\/\\\/rugbysanmauro.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rugbysanmauro.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Logo-San-Mauro-Rugby-scudo.webp\",\"contentUrl\":\"https:\\\/\\\/rugbysanmauro.it\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Logo-San-Mauro-Rugby-scudo.webp\",\"width\":512,\"height\":512,\"caption\":\"ASD Rugby San Mauro\"},\"image\":{\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rugbysanmauro\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rugbysanmauro\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rugbysanmauro.it\\\/#\\\/schema\\\/person\\\/5752ef3556e19dd3efee8f9616d69256\",\"name\":\"Francesco002\",\"sameAs\":[\"https:\\\/\\\/rugbysanmauro.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"aggiornamento del 5 marzo covid -19 disposizioni - Rugby San Mauro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/","og_locale":"it_IT","og_type":"article","og_title":"aggiornamento del 5 marzo covid -19 disposizioni - Rugby San Mauro","og_description":"In riferimento al comunicato della Presidenza del Consiglio del 4 marzo \u201920 riguardante le regole comportamentali e prudenziali per il contrasto e contenimento della diffusione del COVID-19, la Societ\u00e0 Rugby San Mauro ha deciso di interrompere tutte le attivit\u00e0 quali : allenamenti, partite amichevoli e tutte le attivit\u00e0 di preparazione atletica per tutte le categorie [&hellip;]","og_url":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/","og_site_name":"Rugby San Mauro","article_publisher":"https:\/\/www.facebook.com\/rugbysanmauro\/","article_published_time":"2020-03-04T23:00:00+00:00","author":"Francesco002","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/#article","isPartOf":{"@id":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/"},"author":{"name":"Francesco002","@id":"https:\/\/rugbysanmauro.it\/#\/schema\/person\/5752ef3556e19dd3efee8f9616d69256"},"headline":"aggiornamento del 5 marzo covid -19 disposizioni","datePublished":"2020-03-04T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/"},"wordCount":165,"commentCount":0,"publisher":{"@id":"https:\/\/rugbysanmauro.it\/#organization"},"articleSection":["Archivio"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/","url":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/","name":"aggiornamento del 5 marzo covid -19 disposizioni - Rugby San Mauro","isPartOf":{"@id":"https:\/\/rugbysanmauro.it\/#website"},"datePublished":"2020-03-04T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rugbysanmauro.it\/index.php\/aggiornamento-del-5-marzo-covid-19-disposizioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rugbysanmauro.it\/"},{"@type":"ListItem","position":2,"name":"aggiornamento del 5 marzo covid -19 disposizioni"}]},{"@type":"WebSite","@id":"https:\/\/rugbysanmauro.it\/#website","url":"https:\/\/rugbysanmauro.it\/","name":"Rugby San Mauro","description":"","publisher":{"@id":"https:\/\/rugbysanmauro.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rugbysanmauro.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/rugbysanmauro.it\/#organization","name":"ASD Rugby San Mauro","url":"https:\/\/rugbysanmauro.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rugbysanmauro.it\/#\/schema\/logo\/image\/","url":"https:\/\/rugbysanmauro.it\/wp-content\/uploads\/2025\/10\/Logo-San-Mauro-Rugby-scudo.webp","contentUrl":"https:\/\/rugbysanmauro.it\/wp-content\/uploads\/2025\/10\/Logo-San-Mauro-Rugby-scudo.webp","width":512,"height":512,"caption":"ASD Rugby San Mauro"},"image":{"@id":"https:\/\/rugbysanmauro.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rugbysanmauro\/","https:\/\/www.instagram.com\/rugbysanmauro\/"]},{"@type":"Person","@id":"https:\/\/rugbysanmauro.it\/#\/schema\/person\/5752ef3556e19dd3efee8f9616d69256","name":"Francesco002","sameAs":["https:\/\/rugbysanmauro.it"]}]}},"_links":{"self":[{"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/posts\/1912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/comments?post=1912"}],"version-history":[{"count":0,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/posts\/1912\/revisions"}],"wp:attachment":[{"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/media?parent=1912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/categories?post=1912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rugbysanmauro.it\/index.php\/wp-json\/wp\/v2\/tags?post=1912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}